{"id":3040,"date":"2023-08-04T13:23:12","date_gmt":"2023-08-04T12:23:12","guid":{"rendered":"https:\/\/biocylab.com\/?p=3040"},"modified":"2025-01-21T22:13:44","modified_gmt":"2025-01-21T21:13:44","slug":"laboratoire-cosmetique-a-rabat-decouvrez-biocylab","status":"publish","type":"post","link":"https:\/\/biocylab.com\/en\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/","title":{"rendered":"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3040\" class=\"elementor elementor-3040\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6912fbd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6912fbd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-673c292\" data-id=\"673c292\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60f2ab3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"60f2ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Expertise cosm\u00e9tique \u00e0 votre service : r\u00e9alisez vos projets avec succ\u00e8s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32af786 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"32af786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre laboratoire cosm\u00e9tique \u00e0 Rabat vous propose des services cl\u00e9 en main ainsi que des conseils d\u2019experts reprenant plusieurs palettes allant de la formulation \u00e0 la fabrication de vos propres produits cosm\u00e9tiques.<\/p><p>Recevez des conseils personnalis\u00e9s en cosm\u00e9tologie gr\u00e2ce \u00e0 notre \u00e9quipe d&#8217;experts pluridisciplinaires. Bas\u00e9 \u00e0 Rabat, notre laboratoire cosm\u00e9tique propose une gamme compl\u00e8te de services, comprenant le full service, le private label et le travail \u00e0 fa\u00e7on, pour r\u00e9pondre \u00e0 tous vos besoins en mati\u00e8re de cosm\u00e9tiques.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-215056d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"215056d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3dcec87\" data-id=\"3dcec87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2cd341 elementor-widget elementor-widget-image\" data-id=\"e2cd341\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"878\" src=\"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-scaled.webp\" class=\"attachment-full size-full wp-image-5923\" alt=\"BIOCYLAB Laboratoire : Expert en ingr\u00e9dients naturels, cr\u00e9ateur de marques cosm\u00e9tiques personnalis\u00e9es pour le march\u00e9 marocain.\" srcset=\"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-scaled.webp 2560w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-300x103.webp 300w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-1024x351.webp 1024w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-768x264.webp 768w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-1536x527.webp 1536w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-2048x703.webp 2048w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-18x6.webp 18w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-600x206.webp 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e55db9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e55db9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67eea29\" data-id=\"67eea29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0dbc1eb elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0dbc1eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Explorez notre \u00e9quipe d'experts d\u00e9vou\u00e9s, pr\u00eats \u00e0 vous offrir des conseils cosm\u00e9tiques de premi\u00e8re qualit\u00e9.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d09d2c0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d09d2c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous collaborons \u00e9troitement avec vous tout au long du processus, de la conception \u00e0 la mise en march\u00e9 de vos produits cosm\u00e9tiques, afin de garantir une approche personnalis\u00e9e et adapt\u00e9e \u00e0 vos besoins.<\/p><p>Notre laboratoire dispose d&#8217;\u00e9quipements de pointe de derni\u00e8re g\u00e9n\u00e9ration et d&#8217;un p\u00f4le d\u00e9di\u00e9 au contr\u00f4le de qualit\u00e9, nous permettant ainsi de cr\u00e9er des produits cosm\u00e9tiques exceptionnels.<\/p><p>Vous d\u00e9sirez en savoir davantage sur nos m\u00e9thodes de fabrication de produits cosm\u00e9tiques \u00e0 Rabat ? <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/wa.link\/08jxhz\"><strong>N&#8217;h\u00e9sitez pas \u00e0 nous contacter pour en savoir plus !<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8631685 elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"8631685\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/wa.link\/08jxhz\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">WhatsApp 24H\/7 <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3487457 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3487457\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-508bb3e\" data-id=\"508bb3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d1c1f2 elementor-widget elementor-widget-image\" data-id=\"7d1c1f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"878\" src=\"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-scaled.webp\" class=\"attachment-full size-full wp-image-5914\" alt=\"BIOCYLAB Laboratoire : Innovateur en cosm\u00e9tique naturelle, offrant des solutions sur mesure avec des ingr\u00e9dients de qualit\u00e9 pour le march\u00e9 marocain.\" srcset=\"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-scaled.webp 2560w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-300x103.webp 300w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-1024x351.webp 1024w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-768x264.webp 768w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-1536x527.webp 1536w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-2048x703.webp 2048w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-18x6.webp 18w, https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-24-600x206.webp 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-beb248c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"beb248c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c126865\" data-id=\"c126865\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bf3784 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5bf3784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre offre est structur\u00e9e autour de 3 propositions | Laboratoire Cosm\u00e9tique \u00e0 Rabat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-551e79a elementor-widget elementor-widget-heading\" data-id=\"551e79a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nous vous offrons notre savoir faire en fournissant des services comme suit :\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6c3b72 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e6c3b72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"color: #ff9900;\"><strong>Le full service<\/strong><\/span> : une approche hautement performante pour concr\u00e9tiser votre concept en un produit de beaut\u00e9 abouti. Notre m\u00e9thode garantit une d\u00e9finition technique, \u00e9conomique, scientifique et commerciale (marketing) du produit, assurant ainsi son succ\u00e8s sur tous les plans.<\/li><li><span style=\"color: #ff9900;\"><strong>Le private label<\/strong><\/span> : une opportunit\u00e9 de personnaliser vos propres produits cosm\u00e9tiques. Choisissez parmi une vaste gamme de formules pour cr\u00e9er des produits qui vous ressemblent.<\/li><li><span style=\"color: #ff9900;\"><strong>Le fa\u00e7onnage<\/strong><\/span> : nous r\u00e9alisons la fabrication de vos produits cosm\u00e9tiques selon votre formule exclusive. Notre laboratoire prend en charge la production et le conditionnement de vos produits, r\u00e9pondant ainsi \u00e0 vos besoins sp\u00e9cifiques.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cb30b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cb30b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dce6783\" data-id=\"dce6783\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-922fdcc elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"922fdcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre Valeur-ajout\u00e9e\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3b2007 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e3b2007\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">En optant pour notre service, vous b\u00e9n\u00e9ficierez de :<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2602e8d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2602e8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u00c9largissez votre gamme de produits en ajoutant de nouvelles r\u00e9f\u00e9rences ou variantes \u00e0 votre catalogue;<\/li><li>Fid\u00e9lisez votre client\u00e8le;<\/li><li>Am\u00e9liorez la notori\u00e9t\u00e9 de votre marque;<\/li><li>Associez-vous \u00e0 un partenaire professionnel qui vous accompagne de la phase de conception \u00e0 la mise sur le march\u00e9;<\/li><li>Trouvez des solutions sur mesure;<\/li><li>Gagnez de nouveaux march\u00e9s;<\/li><li>Associez-vous \u00e0 un partenaire professionnel qui vous accompagne de la phase de conception \u00e0 la mise sur le march\u00e9;<\/li><li>Cr\u00e9ez des produits exclusifs;<\/li><li>Favorisez l\u2019innovation gr\u00e2ce \u00e0 notre service de R&amp;D.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddb9ce7 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ddb9ce7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos principales caract\u00e9ristiques :\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5e4f68 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c5e4f68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Une \u00e9quipe d\u2019exp\u00e9rience et multidisciplinaire<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68badc0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"68badc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">De fortes valeurs :\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b49ec1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0b49ec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Satisfaction Client<\/li><li>Qualit\u00e9 premium<\/li><li>\u00c9co responsable<\/li><li>R\u00e9activit\u00e9 et Flexibilit\u00e9 via notre <span style=\"color: #ff9900;\"><strong><a style=\"color: #ff9900;\" href=\"http:\/\/wa.link\/08jxhz\">Hotline WhatsApp<\/a><\/strong><\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48b47b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48b47b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-662a3b3\" data-id=\"662a3b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-731498b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"731498b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c0 propos de notre laboratoire cosm\u00e9tique \u00e0 Rabat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0ebaf6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a0ebaf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre laboratoire cosm\u00e9tique \u00e0 Rabat offres plusieurs services de la formulation en passant par le design et bien s\u00fbr la production de vos produits cosm\u00e9tiques tout en respectant des normes de fabrication rigoureuses. Pour nos produits bio nous utilisons seulement des mati\u00e8res premi\u00e8res certifi\u00e9es . N\u2019h\u00e9sitez pas \u00e0 d\u00e9couvrir notre <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/biocylab.com\/biocylab-creation-de-marque-cosmetique-au-maroc-france\/\"><strong>SOLUTION CL\u00c9 EN MAIN.<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f252ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f252ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5dd73e1\" data-id=\"5dd73e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32b4866 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"32b4866\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un laboratoire cosm\u00e9tique innovant \u00e0 Rabat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ecfc40 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6ecfc40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre laboratoire cosm\u00e9tique situ\u00e9 \u00e0 Rabat consacre 10% de son chiffre d&#8217;affaires \u00e0 la recherche et au d\u00e9veloppement de produits et solutions r\u00e9pondant \u00e0 vos besoins les plus exigeants.<\/p><p>Nous offrons des produits et services de haute valeur \u00e0 divers partenaires commerciaux, tels que des marques cosm\u00e9tiques, des distributeurs, des cha\u00eenes h\u00f4teli\u00e8res, et bien d&#8217;autres encore. Nous sommes \u00e9galement sous-traitants pour plusieurs autres laboratoires.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8ce10d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8ce10d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd1b60e\" data-id=\"dd1b60e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9496476 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9496476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quels sont les avantages de collaborer avec notre laboratoire cosm\u00e9tique \u00e0 Rabat?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17d592b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"17d592b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous vous offrons LA solution cl\u00e9 en main chez <span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"https:\/\/biocylab.com\/\"><strong>BIOCYLAB<\/strong><\/a><\/span> comprenant :<\/p><ul><li>Analyse et d\u00e9finition de vos besoins sp\u00e9cifiques<\/li><li>Formulation personnalis\u00e9e de vos produits<\/li><li>Fabrication de haute qualit\u00e9 de vos produits cosm\u00e9tiques<\/li><li>Conception attrayante de votre packaging<\/li><li>Conseils experts en mati\u00e8re de marketing pour promouvoir vos produits.<\/li><\/ul><p>Notre mission est de prendre en charge int\u00e9gralement la fabrication de vos produits, vous permettant ainsi de vous concentrer sur l&#8217;essentiel :<span style=\"color: #ff9900;\"> <a style=\"color: #ff9900;\" href=\"https:\/\/pureagency.ma\/\"><strong>la commercialisation !<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-446ed99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"446ed99\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cf2c102\" data-id=\"cf2c102\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9c26ac2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c26ac2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-eef7a17\" data-id=\"eef7a17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc9d557 elementor-widget elementor-widget-heading\" data-id=\"cc9d557\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact rapide<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05fada4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"05fada4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour toute question concernant un produit, un service ou une commande, n\u2019h\u00e9sitez pas \u00e0 nous contacter via l\u2019un des moyens suivants :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-91384eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91384eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a94a3b\" data-id=\"4a94a3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-810dbeb elementor-widget elementor-widget-metform\" data-id=\"810dbeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"metform.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"mf-response-props-id-504\" data-previous-steps-style=\"\" data-editswitchopen=\"\" data-response_type=\"alert\" data-erroricon=\"fas fa-exclamation-triangle\" data-successicon=\"fas fa-check\" data-messageposition=\"top\" class=\"   mf-scroll-top-no\">\n\t\t<div class=\"formpicker_warper formpicker_warper_editable\" data-metform-formpicker-key=\"504\" >\n\t\t\t\t\n\t\t\t<div class=\"mf-widget-container\">\n\t\t\t\t\r\n\t\t<div\r\n\t\t\tid=\"metform-wrap-810dbeb-504\"\r\n\t\t\tclass=\"mf-form-wrapper\"\r\n\t\t\tdata-form-id=\"504\"\r\n\t\t\tdata-action=\"https:\/\/biocylab.com\/en\/wp-json\/metform\/v1\/entries\/insert\/504\"\r\n\t\t\tdata-wp-nonce=\"c89cb46eb1\"\r\n\t\t\tdata-form-nonce=\"15b9c733fc\"\r\n\t\t\tdata-quiz-summery = \"false\"\r\n\t\t\tdata-save-progress = \"false\"\r\n\t\t\tdata-form-type=\"general-form\"\r\n\t\t\tdata-stop-vertical-effect=\"\"\r\n\t\t\t><\/div>\r\n\r\n\r\n\t\t<!----------------------------- \r\n\t\t\t* controls_data : find the the props passed indie of data attribute\r\n\t\t\t* props.SubmitResponseMarkup : contains the markup of error or success message\r\n\t\t\t* https:\/\/developer.mozilla.org\/en-US\/docs\/Web\/JavaScript\/Reference\/Template_literals\r\n\t\t--------------------------- -->\r\n\r\n\t\t\t\t<script type=\"text\/mf\" class=\"mf-template\">\r\n\t\t\tfunction controls_data (value){\r\n\t\t\t\tlet currentWrapper = \"mf-response-props-id-504\";\r\n\t\t\t\tlet currentEl = document.getElementById(currentWrapper);\r\n\t\t\t\t\r\n\t\t\t\treturn currentEl ? currentEl.dataset[value] : false\r\n\t\t\t}\r\n\r\n\r\n\t\t\tlet is_edit_mode = '' ? true : false;\r\n\t\t\tlet message_position = controls_data('messageposition') || 'top';\r\n\r\n\t\t\t\r\n\t\t\tlet message_successIcon = controls_data('successicon') || '';\r\n\t\t\tlet message_errorIcon = controls_data('erroricon') || '';\r\n\t\t\tlet message_editSwitch = controls_data('editswitchopen') === 'yes' ? true : false;\r\n\t\t\tlet message_proClass = controls_data('editswitchopen') === 'yes' ? 'mf_pro_activated' : '';\r\n\t\t\t\r\n\t\t\tlet is_dummy_markup = is_edit_mode && message_editSwitch ? true : false;\r\n\r\n\t\t\t\r\n\t\t\treturn html`\r\n\t\t\t\t<form\r\n\t\t\t\t\tclassName=\"metform-form-content\"\r\n\t\t\t\t\tref=${parent.formContainerRef}\r\n\t\t\t\t\tonSubmit=${ validation.handleSubmit( parent.handleFormSubmit ) }\r\n\t\t\t\t\r\n\t\t\t\t\t>\r\n\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'top' ?  props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' :  message_position === 'top' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\r\n\t\t\t\t\t<!--------------------------------------------------------\r\n\t\t\t\t\t*** IMPORTANT \/ DANGEROUS ***\r\n\t\t\t\t\t${html``} must be used as in immediate child of \"metform-form-main-wrapper\"\r\n\t\t\t\t\tclass otherwise multistep form will not run at all\r\n\t\t\t\t\t---------------------------------------------------------->\r\n\r\n\t\t\t\t\t<div className=\"metform-form-main-wrapper\" key=${'hide-form-after-submit'} ref=${parent.formRef}>\r\n\t\t\t\t\t${html`\r\n\t\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" key=\"2\" data-elementor-id=\"504\" className=\"elementor elementor-504\">\n\t\t\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-5363778 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5363778\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a20ee06\" data-id=\"a20ee06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-b34d9c1 elementor-widget elementor-widget-mf-listing-fname\" data-id=\"b34d9c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-listing-fname&quot;}\" data-widget_type=\"mf-listing-fname.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-b34d9c1\">\n\t\t\t\t\t${ parent.decodeEntities(`Pr\u00e9nom et Nom`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n\t\t\t\n\t\t\t<input type=\"text\" className=\"mf-input \" id=\"mf-input-text-b34d9c1\" \n\t\t\t\tname=\"mf-listing-fname\" \n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Entrez votre Pr\u00e9nom et Nom`) } \"\n\t\t\t\tonInput=${ parent.handleChange }\n\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-listing-fname'] ? 'true' : 'false'}\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"Ce champ est obligatoire.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el) }\n\t\t\t\t\t\t\t\/>\n\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-listing-fname\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e68917c\" data-id=\"e68917c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-f79af92 elementor-widget elementor-widget-mf-listing-lname\" data-id=\"f79af92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-listing-lname&quot;}\" data-widget_type=\"mf-listing-lname.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-f79af92\">\n\t\t\t\t\t${ parent.decodeEntities(`Pays et Ville`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n\t\t\t\n\t\t\t<input type=\"text\" className=\"mf-input \" id=\"mf-input-text-f79af92\" \n\t\t\t\tname=\"mf-listing-lname\" \n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Entrez votre Pays et votre Ville`) } \"\n\t\t\t\tonInput=${ parent.handleChange }\t\n\n\t\t\t\t\t\t\t\t\taria-invalid=${validation.errors['mf-listing-lname'] ? 'true' : 'false'}\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"Ce champ est obligatoire.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el) }\n\t\t\t\t\t\t\t\t\n\t\t\t\/>\n\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-listing-lname\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-3c0b1da elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c0b1da\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0eed8e5\" data-id=\"0eed8e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-d10fc6c elementor-widget elementor-widget-mf-email\" data-id=\"d10fc6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-email&quot;}\" data-widget_type=\"mf-email.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-email-d10fc6c\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Adresse e-mail`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input \r\n\t\t\t\ttype=\"email\" \r\n\t\t\t\t \r\n\t\t\t\tdefaultValue=\"\" \r\n\t\t\t\tclassName=\"mf-input \" \r\n\t\t\t\tid=\"mf-input-email-d10fc6c\" \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Entrez votre e-mail`) } \" \r\n\t\t\t\t \r\n\t\t\t\tonBlur=${parent.handleChange} onFocus=${parent.handleChange} aria-invalid=${validation.errors['mf-email'] ? 'true' : 'false' } \r\n\t\t\t\tref=${el=> parent.activateValidation({\"message\":\"Ce champ est obligatoire.\",\"emailMessage\":\"Please enter a valid Email address\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t<${validation.ErrorMessage} \r\n\t\t\t\terrors=${validation.errors} \r\n\t\t\t\tname=\"mf-email\" \r\n\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div className=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ae6cf7\" data-id=\"3ae6cf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-e72ebdd elementor-widget elementor-widget-mf-telephone\" data-id=\"e72ebdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-telephone&quot;}\" data-widget_type=\"mf-telephone.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div className=\"mf-input-wrapper\">\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-telephone-e72ebdd\">\n\t\t\t\t\t${ parent.decodeEntities(`T\u00e9l\u00e9phone`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\n\t\t\t\t<\/label>\n\t\t\t\n\t\t\t<input\n\t\t\t\ttype=\"tel\"\n\t\t\t\tclassName=\"mf-input \"\n\t\t\t\tid=\"mf-input-telephone-e72ebdd\" \n\t\t\t\tname=\"mf-telephone\"\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Votre num\u00e9ro t\u00e9l\u00e9phone`) } \"\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\n\t\t\t\t\taria-invalid=${validation.errors['mf-telephone'] ? 'true' : 'false'}\n\t\t\t\t\tref=${el => parent.activateValidation({\"message\":\"Ce champ est obligatoire.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\n\t\t\t\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\n\t\t\t\t\terrors=${validation.errors}\n\t\t\t\t\tname=\"mf-telephone\"\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\n\t\t\t\t\t\/>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-3bf537f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bf537f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-049f4a1\" data-id=\"049f4a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-c7440dc elementor-widget elementor-widget-mf-text\" data-id=\"c7440dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-text&quot;}\" data-widget_type=\"mf-text.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-c7440dc\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Sujet`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\"><\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<input\r\n\t\t\t\ttype=\"text\"\r\n\t\t\t\tclassName=\"mf-input \"\r\n\t\t\t\tid=\"mf-input-text-c7440dc\"\r\n\t\t\t\tname=\"mf-text\"\r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Votre sujet`) } \"\r\n\t\t\t\t\t\t\t\t\tonInput=${parent.handleChange}\r\n\t\t\t\t\tonBlur=${parent.handleChange}\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-text'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${el =>{\r\n\t\t\t\t\t\t\t\t\t\t\t\tparent.activateValidation({\"message\":\"This field is required.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":false,\"expression\":\"null\"}, el)\r\n\t\t\t\t\t}}\r\n\t\t\t\t\t\t\t\t\/>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-text\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section className=\"elementor-section elementor-top-section elementor-element elementor-element-5fa9c7f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fa9c7f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div className=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div className=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8745977\" data-id=\"8745977\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div className=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div className=\"elementor-element elementor-element-2078557 elementor-widget elementor-widget-mf-textarea\" data-id=\"2078557\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;mf_input_name&quot;:&quot;mf-textarea&quot;}\" data-widget_type=\"mf-textarea.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t<div className=\"mf-input-wrapper\">\r\n\t\t\t\t\t\t\t<label className=\"mf-input-label\" htmlFor=\"mf-input-text-area-2078557\">\r\n\t\t\t\t\t${ parent.decodeEntities(`Messages \/ Commentaires`) } \t\t\t\t\t<span className=\"mf-input-required-indicator\">*<\/span>\r\n\t\t\t\t<\/label>\r\n\t\t\t\r\n\t\t\t<textarea className=\"mf-input mf-textarea \" id=\"mf-input-text-area-2078557\"\r\n\t\t\t\tname=\"mf-textarea\" \r\n\t\t\t\tplaceholder=\"${ parent.decodeEntities(`Entrez votre message`) } \"\r\n\t\t\t\tcols=\"30\" rows=\"10\"\r\n\t\t\t\t\t\t\t\t\tonInput=${ parent.handleChange }\r\n\t\t\t\t\taria-invalid=${validation.errors['mf-textarea'] ? 'true' : 'false'}\r\n\t\t\t\t\tref=${ el => parent.activateValidation({\"message\":\"Ce champ est obligatoire.\",\"minLength\":1,\"maxLength\":\"\",\"type\":\"none\",\"required\":true,\"expression\":\"null\"}, el)}\r\n\t\t\t\t\t\t\t\t><\/textarea>\r\n\r\n\t\t\t\t\t\t\t<${validation.ErrorMessage}\r\n\t\t\t\t\terrors=${validation.errors}\r\n\t\t\t\t\tname=\"mf-textarea\"\r\n\t\t\t\t\tas=${html`<span className=\"mf-error-message\"><\/span>`}\r\n\t\t\t\t\t\/>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-2d35449 elementor-widget elementor-widget-spacer\" data-id=\"2d35449\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div className=\"elementor-spacer\">\n\t\t\t<div className=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div className=\"elementor-element elementor-element-51df01b mf-btn--left elementor-widget elementor-widget-mf-button\" data-id=\"51df01b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mf-button.default\">\n\t\t\t\t<div className=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div className=\"mf-btn-wraper \" data-mf-form-conditional-logic-requirement=\"\">\r\n\t\t\t\t\t\t\t<button type=\"submit\" className=\"metform-btn metform-submit-btn \" id=\"\">\r\n\t\t\t\t\t<span>${ parent.decodeEntities(`ENVOYER VOTRE DEMANDE`) } <\/span>\r\n\t\t\t\t<\/button>\r\n\t\t\t        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t`}\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t${is_dummy_markup ? message_position === 'bottom' ? props.ResponseDummyMarkup(message_successIcon, message_proClass) : '' : ''}\r\n\t\t\t\t\t${is_dummy_markup ? ' ' : message_position === 'bottom' ? props.SubmitResponseMarkup`${parent}${state}${message_successIcon}${message_errorIcon}${message_proClass}` : ''}\r\n\t\t\t\t\r\n\t\t\t\t<\/form>\r\n\t\t\t`\r\n\t\t<\/script>\r\n\r\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4da5f50\" data-id=\"4da5f50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61bf5f5\" data-id=\"61bf5f5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-324b383 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"324b383\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f2f8bb4\" data-id=\"f2f8bb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5132832 elementor-widget elementor-widget-heading\" data-id=\"5132832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contactez l'\u00e9quipe BIOCYLAB 24\/7<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0c8880 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a0c8880\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour toute question concernant un produit, un service ou une commande, n\u2019h\u00e9sitez pas \u00e0 nous contacter via l\u2019un des moyens suivants :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5f4fdf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f4fdf5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3560fd9\" data-id=\"3560fd9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf6c454 elementor-widget elementor-widget-image\" data-id=\"cf6c454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"178\" height=\"168\" src=\"https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-359.png\" class=\"attachment-full size-full wp-image-7341\" alt=\"Solutions de soin sur mesure issues d\u2019un laboratoire cosm\u00e9tique \u00e0 Casablanca\" srcset=\"https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-359.png 178w, https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-359-13x12.png 13w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4ca307 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c4ca307\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Appel T\u00e9l\u00e9phonique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-410d249 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"410d249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Appelez-nous pour une assistance directe et personnalis\u00e9e. <strong><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"tel:+212660897229\" data-wplink-edit=\"true\">Cliquez ici pour nous appeler<\/a>.<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4cfe559\" data-id=\"4cfe559\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f29691f elementor-widget elementor-widget-image\" data-id=\"f29691f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"178\" height=\"168\" src=\"https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-360.png\" class=\"attachment-full size-full wp-image-7360\" alt=\"Laboratoire cosm\u00e9tique au Maroc pour les professionnels de la beaut\u00e9\" srcset=\"https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-360.png 178w, https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-360-13x12.png 13w\" sizes=\"(max-width: 178px) 100vw, 178px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-548275d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"548275d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Consultation virtuelle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcae3c3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"bcae3c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Profitez d&#8217;une consultation en ligne avec nos experts. R\u00e9servez d\u00e8s maintenant.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d4ea98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d4ea98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-938c860\" data-id=\"938c860\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a355de elementor-widget elementor-widget-image\" data-id=\"4a355de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"132\" src=\"https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-361.png\" class=\"attachment-full size-full wp-image-7362\" alt=\"Solutions de beaut\u00e9 naturelles issues d\u2019un laboratoire marocain\" srcset=\"https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-361.png 140w, https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-361-13x12.png 13w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbaca22 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"cbaca22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">WhatsApp<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-568a1fa elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"568a1fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contactez-nous instantan\u00e9ment via WhatsApp pour des r\u00e9ponses rapides. <span style=\"color: #000000;\"><strong><a style=\"color: #000000;\" href=\"https:\/\/wa.me\/212660897229\">Cliquez ici pour nous contacter sur WhatsApp<\/a>.<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b62c065\" data-id=\"b62c065\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74a69d2 elementor-widget elementor-widget-image\" data-id=\"74a69d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"132\" src=\"https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-362.png\" class=\"attachment-full size-full wp-image-7361\" alt=\"Laboratoire cosm\u00e9tique \u00e0 Marrakech sp\u00e9cialis\u00e9 dans les produits bio\" srcset=\"https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-362.png 140w, https:\/\/biocylab.com\/wp-content\/uploads\/2024\/10\/Rectangle-362-13x12.png 13w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-311be1e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"311be1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Email<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b984a3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5b984a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Envoyez-nous un email pour des demandes plus d\u00e9taill\u00e9es. R\u00e9ponse rapide garantie. <span style=\"color: #000000;\"><strong><a style=\"color: #000000;\" href=\"mailto:Contact@biocylab.com\">Cliquez ici pour nous envoyer un email<\/a>.<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Expertise cosm\u00e9tique \u00e0 votre service : r\u00e9alisez vos projets avec succ\u00e8s Notre laboratoire cosm\u00e9tique \u00e0 Rabat vous propose des services cl\u00e9 en main ainsi que des conseils d\u2019experts reprenant plusieurs palettes allant de la formulation \u00e0 la fabrication de vos propres produits cosm\u00e9tiques. Recevez des conseils personnalis\u00e9s en cosm\u00e9tologie gr\u00e2ce \u00e0 notre \u00e9quipe d&#8217;experts pluridisciplinaires. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3040","post","type-post","status-publish","format-standard","hentry","category-biocylab-creation-de-marque-cosmetique-sur-mesure-au-maroc-france"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB<\/title>\n<meta name=\"description\" content=\"Notre laboratoire cosm\u00e9tique \u00e0 Rabat vous permet de cr\u00e9er vos produits cosm\u00e9tiques avec notre solution cl\u00e9 en main comprenant le design.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biocylab.com\/en\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB\" \/>\n<meta property=\"og:description\" content=\"Notre laboratoire cosm\u00e9tique \u00e0 Rabat vous permet de cr\u00e9er vos produits cosm\u00e9tiques avec notre solution cl\u00e9 en main comprenant le design.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biocylab.com\/en\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/\" \/>\n<meta property=\"og:site_name\" content=\"BIOCYLAB - Laboratoire cosm\u00e9tique au Maroc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Biocylab-Laboratoires-100089001582630\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-04T12:23:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T21:13:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"878\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"dxnsy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"dxnsy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/\"},\"author\":{\"name\":\"dxnsy\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/#\\\/schema\\\/person\\\/aa10e15a5ef4a0d52b78336aa1a4ae18\"},\"headline\":\"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB\",\"datePublished\":\"2023-08-04T12:23:12+00:00\",\"dateModified\":\"2025-01-21T21:13:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/\"},\"wordCount\":837,\"publisher\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biocylab.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/image-42-scaled.webp\",\"articleSection\":[\"BIOCYLAB Laboratoires\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/\",\"url\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/\",\"name\":\"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biocylab.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/image-42-scaled.webp\",\"datePublished\":\"2023-08-04T12:23:12+00:00\",\"dateModified\":\"2025-01-21T21:13:44+00:00\",\"description\":\"Notre laboratoire cosm\u00e9tique \u00e0 Rabat vous permet de cr\u00e9er vos produits cosm\u00e9tiques avec notre solution cl\u00e9 en main comprenant le design.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biocylab.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/image-42-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/biocylab.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/image-42-scaled.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/biocylab.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/#website\",\"url\":\"https:\\\/\\\/biocylab.com\\\/\",\"name\":\"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique au Maroc - Marrakech.\",\"description\":\"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique au Maroc - Marrakech.\",\"publisher\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/#organization\"},\"alternateName\":\"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique au Maroc - Marrakech.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biocylab.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/#organization\",\"name\":\"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique \u00e0 Marrakech.\",\"alternateName\":\"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique au Maroc - France\",\"url\":\"https:\\\/\\\/biocylab.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biocylab.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-BIOC-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/biocylab.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-BIOC-scaled.webp\",\"width\":2560,\"height\":2560,\"caption\":\"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique \u00e0 Marrakech.\"},\"image\":{\"@id\":\"https:\\\/\\\/biocylab.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Biocylab-Laboratoires-100089001582630\\\/\",\"https:\\\/\\\/www.instagram.com\\\/laboratoires_cosmetique\\\/\",\"https:\\\/\\\/www.kerix.net\\\/fr\\\/annuaire-entreprise\\\/biocylab\",\"https:\\\/\\\/fr.trustpilot.com\\\/review\\\/biocylab.com\",\"https:\\\/\\\/ma.kompass.com\\\/c\\\/biocylab\\\/ma9043093\\\/\",\"https:\\\/\\\/www.goafricaonline.com\\\/ma\\\/832525-biocylab-industrie-cosmetique-casablanca-maroc\\\/feeds\",\"https:\\\/\\\/www.pinterest.com\\\/BIOCYLAB_Laboratoires\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@biocylablaboratoires\\\/featured\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/biocylab-laboratoires\\\/?viewAsMember=true\"],\"description\":\"Laboratoire cosm\u00e9tique au Maroc, sp\u00e9cialis\u00e9 dans la fabrication et la formulation de produits cosm\u00e9tiques sur mesure au Maroc - France\",\"email\":\"contact@biocylab.com\",\"telephone\":\"0660897229\",\"legalName\":\"BIOCYLAB\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/biocylab.com\\\/biocylab-laboratoire-cosmetique-au-maroc-faq\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/biocylab.com\\\/entreprise-biocylab-laboratoire-cosmetique-au-maroc-france-afrique\\\/\",\"diversityStaffingReport\":\"https:\\\/\\\/biocylab.com\\\/entreprise-biocylab-laboratoire-cosmetique-au-maroc-france-afrique\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/biocylab.com\\\/#\\\/schema\\\/person\\\/aa10e15a5ef4a0d52b78336aa1a4ae18\",\"name\":\"dxnsy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25a96eccffad2f2e023d416ee2dc2e531314f00335922afcd2a62ce5c8454264?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25a96eccffad2f2e023d416ee2dc2e531314f00335922afcd2a62ce5c8454264?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25a96eccffad2f2e023d416ee2dc2e531314f00335922afcd2a62ce5c8454264?s=96&d=mm&r=g\",\"caption\":\"dxnsy\"},\"sameAs\":[\"https:\\\/\\\/biocylab.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB","description":"Notre laboratoire cosm\u00e9tique \u00e0 Rabat vous permet de cr\u00e9er vos produits cosm\u00e9tiques avec notre solution cl\u00e9 en main comprenant le design.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biocylab.com\/en\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/","og_locale":"en_US","og_type":"article","og_title":"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB","og_description":"Notre laboratoire cosm\u00e9tique \u00e0 Rabat vous permet de cr\u00e9er vos produits cosm\u00e9tiques avec notre solution cl\u00e9 en main comprenant le design.","og_url":"https:\/\/biocylab.com\/en\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/","og_site_name":"BIOCYLAB - Laboratoire cosm\u00e9tique au Maroc","article_publisher":"https:\/\/www.facebook.com\/p\/Biocylab-Laboratoires-100089001582630\/","article_published_time":"2023-08-04T12:23:12+00:00","article_modified_time":"2025-01-21T21:13:44+00:00","og_image":[{"width":2560,"height":878,"url":"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-scaled.webp","type":"image\/webp"}],"author":"dxnsy","twitter_card":"summary_large_image","twitter_misc":{"Written by":"dxnsy","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/#article","isPartOf":{"@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/"},"author":{"name":"dxnsy","@id":"https:\/\/biocylab.com\/#\/schema\/person\/aa10e15a5ef4a0d52b78336aa1a4ae18"},"headline":"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB","datePublished":"2023-08-04T12:23:12+00:00","dateModified":"2025-01-21T21:13:44+00:00","mainEntityOfPage":{"@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/"},"wordCount":837,"publisher":{"@id":"https:\/\/biocylab.com\/#organization"},"image":{"@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/#primaryimage"},"thumbnailUrl":"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-scaled.webp","articleSection":["BIOCYLAB Laboratoires"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/","url":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/","name":"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB","isPartOf":{"@id":"https:\/\/biocylab.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/#primaryimage"},"image":{"@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/#primaryimage"},"thumbnailUrl":"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-scaled.webp","datePublished":"2023-08-04T12:23:12+00:00","dateModified":"2025-01-21T21:13:44+00:00","description":"Notre laboratoire cosm\u00e9tique \u00e0 Rabat vous permet de cr\u00e9er vos produits cosm\u00e9tiques avec notre solution cl\u00e9 en main comprenant le design.","breadcrumb":{"@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/#primaryimage","url":"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-scaled.webp","contentUrl":"https:\/\/biocylab.com\/wp-content\/uploads\/2023\/08\/image-42-scaled.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/biocylab.com\/laboratoire-cosmetique-a-rabat-decouvrez-biocylab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/biocylab.com\/"},{"@type":"ListItem","position":2,"name":"Laboratoire cosm\u00e9tique \u00e0 Rabat | D\u00e9couvrez BIOCYLAB"}]},{"@type":"WebSite","@id":"https:\/\/biocylab.com\/#website","url":"https:\/\/biocylab.com\/","name":"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique au Maroc - Marrakech.","description":"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique au Maroc - Marrakech.","publisher":{"@id":"https:\/\/biocylab.com\/#organization"},"alternateName":"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique au Maroc - Marrakech.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biocylab.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/biocylab.com\/#organization","name":"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique \u00e0 Marrakech.","alternateName":"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique au Maroc - France","url":"https:\/\/biocylab.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/biocylab.com\/#\/schema\/logo\/image\/","url":"https:\/\/biocylab.com\/wp-content\/uploads\/2022\/12\/LOGO-BIOC-scaled.webp","contentUrl":"https:\/\/biocylab.com\/wp-content\/uploads\/2022\/12\/LOGO-BIOC-scaled.webp","width":2560,"height":2560,"caption":"BIOCYLAB : Laboratoire cosm\u00e9tique au Maroc | Fournisseur et fabricant de produits cosm\u00e9tique \u00e0 Marrakech."},"image":{"@id":"https:\/\/biocylab.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Biocylab-Laboratoires-100089001582630\/","https:\/\/www.instagram.com\/laboratoires_cosmetique\/","https:\/\/www.kerix.net\/fr\/annuaire-entreprise\/biocylab","https:\/\/fr.trustpilot.com\/review\/biocylab.com","https:\/\/ma.kompass.com\/c\/biocylab\/ma9043093\/","https:\/\/www.goafricaonline.com\/ma\/832525-biocylab-industrie-cosmetique-casablanca-maroc\/feeds","https:\/\/www.pinterest.com\/BIOCYLAB_Laboratoires\/_created\/","https:\/\/www.youtube.com\/@biocylablaboratoires\/featured","https:\/\/www.linkedin.com\/company\/biocylab-laboratoires\/?viewAsMember=true"],"description":"Laboratoire cosm\u00e9tique au Maroc, sp\u00e9cialis\u00e9 dans la fabrication et la formulation de produits cosm\u00e9tiques sur mesure au Maroc - France","email":"contact@biocylab.com","telephone":"0660897229","legalName":"BIOCYLAB","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/biocylab.com\/biocylab-laboratoire-cosmetique-au-maroc-faq\/","ownershipFundingInfo":"https:\/\/biocylab.com\/entreprise-biocylab-laboratoire-cosmetique-au-maroc-france-afrique\/","diversityStaffingReport":"https:\/\/biocylab.com\/entreprise-biocylab-laboratoire-cosmetique-au-maroc-france-afrique\/"},{"@type":"Person","@id":"https:\/\/biocylab.com\/#\/schema\/person\/aa10e15a5ef4a0d52b78336aa1a4ae18","name":"dxnsy","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/25a96eccffad2f2e023d416ee2dc2e531314f00335922afcd2a62ce5c8454264?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25a96eccffad2f2e023d416ee2dc2e531314f00335922afcd2a62ce5c8454264?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25a96eccffad2f2e023d416ee2dc2e531314f00335922afcd2a62ce5c8454264?s=96&d=mm&r=g","caption":"dxnsy"},"sameAs":["https:\/\/biocylab.com"]}]}},"_links":{"self":[{"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/posts\/3040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/comments?post=3040"}],"version-history":[{"count":0,"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/posts\/3040\/revisions"}],"wp:attachment":[{"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/media?parent=3040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/categories?post=3040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/biocylab.com\/en\/wp-json\/wp\/v2\/tags?post=3040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}